{"id":1520,"date":"2025-02-11T12:07:33","date_gmt":"2025-02-11T11:07:33","guid":{"rendered":"https:\/\/clzanardi.it\/cookie-policy-ue\/"},"modified":"2025-02-11T15:40:10","modified_gmt":"2025-02-11T14:40:10","slug":"cookie-policy-ue","status":"publish","type":"page","link":"https:\/\/clzanardi.it\/fr\/cookie-policy-ue\/","title":{"rendered":"Cookie Policy"},"content":{"rendered":"<!-- Legal document generated by Complianz | GDPR\/CCPA Cookie Consent https:\/\/wordpress.org\/plugins\/complianz-gdpr -->\n<div id=\"cmplz-document\" class=\"cmplz-document cookie-statement cmplz-document-eu\"><p><i>Cette politique de cookies a \u00e9t\u00e9 mise \u00e0 jour pour la derni\u00e8re fois le 11\/02\/2025 et s\u2019applique aux citoyens et aux r\u00e9sidents permanents l\u00e9gaux de l\u2019Espace \u00c9conomique Europ\u00e9en et de la Suisse.<\/i><br><\/p><h2>1. Introduction<\/h2><p>Notre site web, <a href=\"https:\/\/clzanardi.it\/fr\">https:\/\/clzanardi.it\/fr<\/a> (ci-apr\u00e8s\u00a0: \u00ab\u00a0le site web\u00a0\u00bb) utilise des cookies et autres technologies li\u00e9es (par simplification, toutes ces technologies sont d\u00e9sign\u00e9es par le terme \u00ab\u00a0cookies\u00a0\u00bb). Des cookies sont \u00e9galement plac\u00e9s par des tierces parties que nous avons engag\u00e9es. Dans le document ci-dessous, nous vous informons de l\u2019utilisation des cookies sur notre site web.<\/p><h2>2. Que sont les cookies\u00a0?<\/h2><p>Un cookie est un petit fichier simple envoy\u00e9 avec les pages de ce site web et stock\u00e9 par votre navigateur sur le disque dur de votre ordinateur ou d\u2019un autre appareil. Les informations qui y sont stock\u00e9es peuvent \u00eatre renvoy\u00e9es \u00e0 nos serveurs ou aux serveurs des tierces parties concern\u00e9es lors d\u2019une visite ult\u00e9rieure.<\/p><h2>3. Que sont les scripts\u00a0?<\/h2><p>Un script est un \u00e9l\u00e9ment de code utilis\u00e9 pour que notre site web fonctionne correctement et de mani\u00e8re interactive. Ce code est ex\u00e9cut\u00e9 sur notre serveur ou sur votre appareil.<\/p><h2>4. Qu\u2019est-ce qu\u2019une balise invisible\u00a0?<\/h2><p>Une balise invisible (ou balise web) est un petit morceau de texte ou d\u2019image invisible sur un site web, utilis\u00e9 pour suivre le trafic sur un site web. Pour ce faire, diverses donn\u00e9es vous concernant sont stock\u00e9es \u00e0 l\u2019aide de balises invisibles.<\/p><h2>5. Cookies<\/h2><p class=\"cmplz-subtitle\">5.1 Cookies techniques ou fonctionnels<\/p><p>Certains cookies assurent le fonctionnement correct de certaines parties du site web et la prise en compte de vos pr\u00e9f\u00e9rences en tant qu\u2019utilisateur. En pla\u00e7ant des cookies fonctionnels, nous vous facilitons la visite de notre site web. Ainsi, vous n\u2019avez pas besoin de saisir \u00e0 plusieurs reprises les m\u00eames informations lors de la visite de notre site web et, par exemple, les \u00e9l\u00e9ments restent dans votre panier jusqu\u2019\u00e0 votre paiement. Nous pouvons placer ces cookies sans votre consentement.<\/p><p class=\"cmplz-subtitle\">5.2 Cookies de marketing\/suivi<\/p><p>Les cookies de marketing\/suivi sont des cookies ou toute autre forme de stockage local, utilis\u00e9s pour cr\u00e9er des profils d\u2019utilisateurs afin d\u2019afficher de la publicit\u00e9 ou de suivre l\u2019utilisateur sur ce site web ou sur plusieurs sites web dans des finalit\u00e9s marketing similaires.<\/p><h2>6. Cookies plac\u00e9s<\/h2><div id=\"cmplz-cookies-overview\"><details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WordPress<\/h3>\n\t\t<p>Fonctionnel<\/p>\n\t\t<label for=\"cmplz_service_wordpress\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wordpress<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wordpress\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wordpress\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons WordPress pour le d\u00e9veloppement du site web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wordpress\/\">Lire la suite<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Ces donn\u00e9es ne sont pas partag\u00e9es avec des tierces parties.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Fonctionnel<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp_preferences_user_\/\">WP_PREFERENCES_USER_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">persistante<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker les pr\u00e9f\u00e9rences des utilisateurs<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wpemojisettingssupports\/\">wpEmojiSettingsSupports<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker les informations du navigateur<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wordpress_test_cookie\/\">wordpress_test_cookie<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">V\u00e9rifier si des cookies peuvent \u00eatre d\u00e9pos\u00e9s<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp_lang\/\">wp_lang<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker les r\u00e9glages de langue<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp-settings\/\">wp-settings-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">persistante<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker les pr\u00e9f\u00e9rences des utilisateurs<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp-settings-time\/\">wp-settings-time-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">1 an<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker les pr\u00e9f\u00e9rences des utilisateurs<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wordpress_logged_in_\/\">wordpress_logged_in_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">persistante<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Garder les utilisateurs connect\u00e9s<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Wistia<\/h3>\n\t\t<p>Marketing, Statistiques<\/p>\n\t\t<label for=\"cmplz_service_wistia\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wistia<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wistia\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wistia\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons Wistia pour l\u2019affichage de vid\u00e9os. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wistia\/\">Lire la suite<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Pour plus d\u2019informations, veuillez lire la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/wistia.com\/privacy\">d\u00e9claration de confidentialit\u00e9 Wistia<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wistia\/wistia\/\">wistia<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">persistante<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker les actions effectu\u00e9es par les utilisateurs sur le site web<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Statistiques<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wistia\/wistia-video-progress\/\">wistia-video-progress-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">persistante<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker si l&#039;utilisateur a vu du contenu int\u00e9gr\u00e9<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Divers<\/h3>\n\t\t<p>Finalit\u00e9 en attente d\u2019enqu\u00eate<\/p>\n\t\t<label for=\"cmplz_service_divers\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service divers<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_divers\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"divers\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Le partage des donn\u00e9es est en cours d\u2019enqu\u00eate<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalit\u00e9 en attente d\u2019enqu\u00eate<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">breakdance_popup_428_count<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">element-studio-tab-primary<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">tmstyle-twig-macros-hash<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">unique_session_id<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">breakdance_copied_element_json_string<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">breakdance-twig-macros<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">tmstyle-twig-macros<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">breakdance_last_used_design_provider<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">flowbite-theme-mode<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">breakdance-twig-macros-hash<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_functional<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_preferences<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_marketing<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_consented_services<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_policy_id<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_statistics<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_banner-status<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">breakdance_clipboard<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_user_data<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<\/div><h2>7. Consentement<\/h2><p>Lorsque vous visitez notre site web pour la premi\u00e8re fois, nous vous montrerons une fen\u00eatre contextuelle avec une explication sur les cookies. D\u00e8s que vous cliquez sur \u00ab\u00a0Salva preferenze\u00a0\u00bb vous nous autorisez \u00e0 utiliser les cat\u00e9gories de cookies et d\u2019extensions que vous avez s\u00e9lectionn\u00e9s dans la fen\u00eatre contextuelle, comme d\u00e9crit dans la pr\u00e9sente politique de cookies. Vous pouvez d\u00e9sactiver l\u2019utilisation des cookies via votre navigateur, mais veuillez noter que notre site web pourrait ne plus fonctionner correctement.<\/p><p class=\"cmplz-subtitle\">7.1 G\u00e9rez vos r\u00e9glages de consentement<\/p><div id=\"cmplz-manage-consent-container-nojavascript\">Vous avez charg\u00e9 la politique de cookies sans le support de javascript.&nbsp;Sur AMP, vous pouvez utiliser l\u2019onglet de gestion du consentement en bas de la page.<\/div><div id=\"cmplz-manage-consent-container\" name=\"cmplz-manage-consent-container\" class=\"cmplz-manage-consent-container\"><\/div><h2>8. Activer\/d\u00e9sactiver et supprimer les cookies<\/h2><p>Vous pouvez utiliser votre navigateur internet pour supprimer automatiquement ou manuellement les cookies. Vous pouvez \u00e9galement sp\u00e9cifier que certains cookies ne peuvent pas \u00eatre plac\u00e9s. Une autre option consiste \u00e0 modifier les r\u00e9glages de votre navigateur Internet afin que vous receviez un message \u00e0 chaque fois qu\u2019un cookie est plac\u00e9. Pour plus d\u2019informations sur ces options, reportez-vous aux instructions de la section Aide de votre navigateur.<\/p><p>Veuillez noter que notre site web peut ne pas marcher correctement si tous les cookies sont d\u00e9sactiv\u00e9s. Si vous supprimez les cookies dans votre navigateur, ils seront de nouveau plac\u00e9s apr\u00e8s votre consentement lorsque vous revisiterez notre site web.<\/p><h2>9. Vos droits concernant les donn\u00e9es personnelles<\/h2><p>Vous avez les droits suivants concernant vos donn\u00e9es personnelles\u00a0:<\/p><ul>\n                    <li>Vous avez le droit de savoir pourquoi vos donn\u00e9es personnelles sont n\u00e9cessaires, ce qui leur arrivera et combien de temps elles seront conserv\u00e9es.<\/li>\n                    <li>Droit d\u2019acc\u00e8s\u00a0: vous avez le droit d\u2019acc\u00e9der \u00e0 vos donn\u00e9es personnelles que nous connaissons.<\/li>\n                    <li>Droit de rectification\u00a0: vous avez le droit \u00e0 tout moment de compl\u00e9ter, corriger, faire supprimer ou bloquer vos donn\u00e9es personnelles.<\/li>\n                    <li>Si vous nous donnez votre consentement pour le traitement de vos donn\u00e9es, vous avez le droit de r\u00e9voquer ce consentement et de faire supprimer vos donn\u00e9es personnelles.<\/li>\n                    <li>Droit de transf\u00e9rer vos donn\u00e9es\u00a0: vous avez le droit de demander toutes vos donn\u00e9es personnelles au responsable du traitement et de les transf\u00e9rer dans leur int\u00e9gralit\u00e9 \u00e0 un autre responsable du traitement.<\/li>\n                    <li>Droit d\u2019opposition\u00a0: vous pouvez vous opposer au traitement de vos donn\u00e9es. Nous obtemp\u00e9rerons, \u00e0 moins que certaines raisons ne justifient ce traitement.<\/li>\n                <\/ul><p>Pour exercer ces droits, veuillez nous contacter. Veuillez vous r\u00e9f\u00e9rer aux coordonn\u00e9es au bas de cette politique de cookies. Si vous avez une plainte concernant la fa\u00e7on dont nous traitons vos donn\u00e9es, nous aimerions en \u00eatre inform\u00e9s, mais vous avez \u00e9galement le droit de d\u00e9poser une plainte aupr\u00e8s de l\u2019autorit\u00e9 de contr\u00f4le (l\u2019autorit\u00e9 charg\u00e9e de la protection des donn\u00e9es).<\/p><h2>10. Coordonn\u00e9es<\/h2><p>Pour des questions et\/ou des commentaires sur notre politique de cookies et cette d\u00e9claration, veuillez nous contacter en utilisant les coordonn\u00e9es suivantes\u00a0:<\/p><p><span class=\"cmplz-contact-organisation\">COOPERATIVA LAVORATORI ZANARDI<\/span><br>\n                      <span class=\"cmplz-contact-address\">Via Venezuela, 3, 35127 Padova PD, Italia<\/span><br>\n                      <span class=\"cmplz-contact-country\">Italie<\/span><br>\n                    Site web\u00a0: <span class=\"cmplz-contact-domain\"><a href=\"https:\/\/clzanardi.it\/fr\">https:\/\/clzanardi.it\/fr<\/a><\/span><br>\n                    E-mail\u00a0: <span class=\"cmplz-contact-email\"><span class=\"cmplz-obfuscate\">&#105;&#110;f&#111;@<span class=\"cmplz-fmail-domain\">&#101;&#120;.&#099;&#111;m<\/span>&#099;&#108;&#122;an&#097;&#114;di&#046;&#105;&#116;<\/span><\/span><br>\n                    <span class=\"cmplz-contact-telephone\">Phone number: +390498069511<\/span><\/p><p>Cette politique de cookies a \u00e9t\u00e9 synchronis\u00e9e avec <a href=\"https:\/\/cookiedatabase.org\/\" target=\"_blank\" rel=\"noopener\">cookiedatabase.org<\/a> le 27\/01\/2026.<\/p><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_breakdance_hide_in_design_set":false,"_breakdance_tags":"","footnotes":""},"class_list":["post-1520","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/clzanardi.it\/fr\/wp-json\/wp\/v2\/pages\/1520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clzanardi.it\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/clzanardi.it\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/clzanardi.it\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clzanardi.it\/fr\/wp-json\/wp\/v2\/comments?post=1520"}],"version-history":[{"count":1,"href":"https:\/\/clzanardi.it\/fr\/wp-json\/wp\/v2\/pages\/1520\/revisions"}],"predecessor-version":[{"id":1526,"href":"https:\/\/clzanardi.it\/fr\/wp-json\/wp\/v2\/pages\/1520\/revisions\/1526"}],"wp:attachment":[{"href":"https:\/\/clzanardi.it\/fr\/wp-json\/wp\/v2\/media?parent=1520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}